{"id":33,"count":1,"description":"Nous offrons trois tailles diff\u00e9rentes de plates-formes de forage. La GTB 700 est la plus petite, la GTB 1500 est de taille moyenne et la GTB 2000 est la version puissante.","link":"https:\/\/nordmeyer-dev.projekte-web.com\/fr\/product-category\/forage\/","name":"MACHINES DE FORAGE","slug":"forage","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/nordmeyer-dev.projekte-web.com\/fr\/wp-json\/wp\/v2\/product_cat\/33"}],"collection":[{"href":"https:\/\/nordmeyer-dev.projekte-web.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/nordmeyer-dev.projekte-web.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/nordmeyer-dev.projekte-web.com\/fr\/wp-json\/wp\/v2\/product?product_cat=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}